{"id":50,"count":1,"description":"","link":"https:\/\/www.chemins-khatovar.com\/site\/tag\/vandermeer\/","name":"Vandermeer","slug":"vandermeer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/tags\/50"}],"collection":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/posts?tags=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}