{"id":1,"date":"2010-10-09T14:59:47","date_gmt":"2010-10-09T12:59:47","guid":{"rendered":"http:\/\/www.chemins-khatovar.com\/site\/?p=1"},"modified":"2010-10-18T10:23:02","modified_gmt":"2010-10-18T08:23:02","slug":"bonjour-tout-le-monde","status":"publish","type":"post","link":"https:\/\/www.chemins-khatovar.com\/site\/2010\/10\/bonjour-tout-le-monde\/","title":{"rendered":"Ouverture du site"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Les Chemins de Khatovar\" src=\"http:\/\/www.chemins-khatovar.com\/forum\/styles\/Mylcastel\/imageset\/site_logo.gif\" alt=\"\" width=\"468\" height=\"59\" \/>Bienvenue sur le site des chemins de Khatovar.<\/p>\n<p style=\"text-align: justify;\">Le site vient juste d&rsquo;ouvrir donc pour le moment il n&rsquo;y a pas grand chose dessus, mais cela ne saurait tarder alors patience, en attendant n&rsquo;h\u00e9sitez pas \u00e0 passer par le forum.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur le site des chemins de Khatovar. Le site vient juste d&rsquo;ouvrir donc pour le moment il n&rsquo;y a pas grand chose dessus, mais cela ne saurait tarder alors patience, en attendant n&rsquo;h\u00e9sitez pas \u00e0 passer par le forum.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[8,9],"_links":{"self":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":10,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":133,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/posts\/1\/revisions\/133"}],"wp:attachment":[{"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chemins-khatovar.com\/site\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}